{"id":99978,"date":"2021-11-17T18:24:45","date_gmt":"2021-11-17T17:24:45","guid":{"rendered":"https:\/\/www.uckg.org\/pt\/?p=99978"},"modified":"2023-04-24T10:27:19","modified_gmt":"2023-04-24T09:27:19","slug":"o-que-significa-servir-a-deus","status":"publish","type":"post","link":"https:\/\/www.uckg.org\/pt\/o-que-significa-servir-a-deus\/","title":{"rendered":"O que significa servir a Deus?"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.uckg.org\/pt\/wp-content\/uploads\/2021\/11\/shutterstock_1947037777-1.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-99979 size-full\" title=\"O que significa servir a Deus?\" src=\"https:\/\/www.uckg.org\/pt\/wp-content\/uploads\/2021\/11\/shutterstock_1947037777-1.png\" alt=\"O que significa servir a Deus?\" width=\"883\" height=\"386\" srcset=\"https:\/\/www.uckg.org\/pt\/wp-content\/uploads\/2021\/11\/shutterstock_1947037777-1.png 883w, https:\/\/www.uckg.org\/pt\/wp-content\/uploads\/2021\/11\/shutterstock_1947037777-1-300x131.png 300w, https:\/\/www.uckg.org\/pt\/wp-content\/uploads\/2021\/11\/shutterstock_1947037777-1-768x336.png 768w, https:\/\/www.uckg.org\/pt\/wp-content\/uploads\/2021\/11\/shutterstock_1947037777-1-500x219.png 500w\" sizes=\"(max-width: 883px) 100vw, 883px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Deus faz uma promessa \u00e0queles que O servem \u2013 uma promessa de fazer a diferen\u00e7a na vida de Seus servos. No entanto, para entender isso, \u00e9 importante primeiro apreciar o que significa servi-Lo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.uckg.org\/pt\/como-amadurecer\/\">Servir a Deus<\/a> significa simplesmente consider\u00e1-Lo em tudo o que voc\u00ea faz, permanecer fiel \u00e0 Sua Palavra e viver uma vida que O honra. Antes de come\u00e7ar um novo emprego, come\u00e7ar um relacionamento ou se mudar para uma nova casa, voc\u00ea costuma falar com Deus sobre isso? Voc\u00ea pede a Ele que lhe mostre quais decis\u00f5es voc\u00ea deve tomar? Ser um servo de Deus significa buscar Sua orienta\u00e7\u00e3o e seguir com o que Ele sabe ser melhor para sua vida.<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u201cSe algu\u00e9m me serve, siga-me, e onde eu estiver, ali estar\u00e1 tamb\u00e9m o meu servo. E, se algu\u00e9m me servir, meu Pai o honrar\u00e1.&#8221;<\/strong><\/em> (Jo\u00e3o 12:26).<\/p>\n<p style=\"text-align: justify;\">A diferen\u00e7a da qual falamos \u00e9 da presen\u00e7a do Esp\u00edrito Santo dentro de Seus servos, Deus dar\u00e1 aos Seus servos tudo que eles precisam, e com o Esp\u00edrito Santo h\u00e1 abund\u00e2ncia de alegria. Quando Deus coloca Sua presen\u00e7a em voc\u00ea, h\u00e1 uma fonte fluindo que mata sua sede. Servir a Deus \u00e9 levar <a href=\"https:\/\/www.uckg.org\/pt\/vencedora-na-vida-financeira\/\">uma vida de felicidade<\/a>, isso n\u00e3o significa que ser\u00e1 um mar de rosas, mas significa que Deus prover\u00e1 para voc\u00ea e sendo Seu servo, nada lhe faltar\u00e1.<\/p>\n<p style=\"text-align: justify;\">Voc\u00ea quer ser um servo de Deus? Um servo que O segue por quem Ele \u00e9 e n\u00e3o apenas pelo que voc\u00ea pode receber em troca? Nossas reuni\u00f5es de domingo \u00e0s 10h da manh\u00e3, t\u00eam como objetivo ajudar as pessoas a se conectarem com Deus, a serem capacitadas e ensinadas a usar sua f\u00e9 para alcan\u00e7ar o que precisam para suas vidas.<\/p>\n<p style=\"text-align: justify;\">Se voc\u00ea deseja se tornar um servo de Deus, podemos orientar e ajudar voc\u00ea nesta jornada. Para mais informa\u00e7\u00f5es sobre a Igreja Universal e o que fazemos, voc\u00ea pode ligar ou WhatsApp para n\u00f3s no <strong>020 7272 1010.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deus faz uma promessa \u00e0queles que O servem \u2013 uma promessa de fazer a diferen\u00e7a na vida de Seus servos. No entanto, para entender isso, \u00e9 importante primeiro apreciar o que significa servi-Lo.<\/p>\n","protected":false},"author":18,"featured_media":99979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[657,1088],"tags":[1742,6244],"class_list":["post-99978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-noticias-da-comunidade","tag-servir-a-deus","tag-uma-vida-de-felicidade"],"_links":{"self":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts\/99978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/comments?post=99978"}],"version-history":[{"count":3,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts\/99978\/revisions"}],"predecessor-version":[{"id":105614,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts\/99978\/revisions\/105614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/media\/99979"}],"wp:attachment":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/media?parent=99978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/categories?post=99978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/tags?post=99978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}