{"id":62856,"date":"2015-11-01T13:00:39","date_gmt":"2015-11-01T13:00:39","guid":{"rendered":"http:\/\/www.uckg.org\/pt\/?p=62856"},"modified":"2021-08-31T10:12:30","modified_gmt":"2021-08-31T08:12:30","slug":"voce-tem-duas-faces","status":"publish","type":"post","link":"https:\/\/www.uckg.org\/pt\/voce-tem-duas-faces\/","title":{"rendered":"Voc\u00ea tem duas faces?"},"content":{"rendered":"<p><a title=\"Voc\u00ea tem duas faces?\" href=\"http:\/\/www.uckg.org\/pt\/wp-content\/uploads\/2015\/10\/2faces.png\" rel=\"\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-62857 size-full\" title=\"Voc\u00ea tem duas faces?\" src=\"http:\/\/www.uckg.org\/pt\/wp-content\/uploads\/2015\/10\/2faces.png\" alt=\"Voc\u00ea tem duas faces?\" width=\"882\" height=\"436\" \/><\/a><\/p>\n<blockquote><p><strong>Uma pessoa de duas caras n\u00e3o \u00e9 fiel aos seus princ\u00edpios. Apesar dela conhecer a diferen\u00e7a entre bom e mau, ela n\u00e3o \u00e9 fiel \u00e0 essa cren\u00e7a\u00a0<\/strong><\/p><\/blockquote>\n<p style=\"text-align: justify;\">Ela se faz de boa para evitar consequ\u00eancias que podem ser m\u00e1s para ela e para ganhar favores, mas quando ela tem a oportunidade de mostrar quem realmente \u00e9, sem temer quais quer consequ\u00eancias, nem mesmo os seu princ\u00edpios a conseguem parar, isto porque ela n\u00e3o \u00e9 fiel \u00e0 eles. Para dar um exemplo expl\u00edcito do significado de ser fiel aos seus <a title=\"Ser uma boa pessoa n\u00e3o \u00e9 suficiente\" href=\"https:\/\/www.uckg.org\/pt\/ser-uma-boa-pessoa-nao-e-suficiente\/\">princ\u00edpios e cren\u00e7as<\/a>, Cl\u00e1udia Brito contou uma hist\u00f3ria de quando ela foi buscar as suas filhas na escola um dia, e encontrou uma delas com arranh\u00f5es na cara.<\/p>\n<p style=\"text-align: justify;\">Como qualquer m\u00e3e, ela quis defender a sua filha e punir o culpado. Ela foi imediatamente para o escrit\u00f3rio do Diretor para entender o que aconteceu. Ela descobriu que uma menina ficou chateada quando ele ouviu a sua filha dizendo para a mais velha que a amava. De raiva, a menina arranhou o rosto da sua filha mais velha. A Cl\u00e1udia pediu para falar com a menina e ap\u00f3s muita resist\u00eancia, o Diretor deixou que as duas conversassem. Quando a Cl\u00e1udia entrou, se abaixou \u00e0 altura da menina, olhou nos seus olhos e disse que a amava. A menina assustada desatou-se em l\u00e1grimas e as duas se abra\u00e7aram. A menina ficou t\u00e3o tocada que ela n\u00e3o quis largar a Cl\u00e1udia. Aquele foi o principio de uma amizade pr\u00f3xima entre as duas.<\/p>\n<p style=\"text-align: justify;\">A Cl\u00e1udia descobriu mais tarde que os pais da menina tinham se divorciado recentemente e ela vivia com uma av\u00f3 <a title=\"Como lidar com o stresse no trabalho\" href=\"https:\/\/www.uckg.org\/pt\/como-lidar-com-o-stresse-no-trabalho\/\">dif\u00edcil de lidar<\/a>. A Cl\u00e1udia conseguiu criar la\u00e7os com essa menina e a ajudou ao longo de um per\u00edodo dif\u00edcil da sua vida. Como \u00e9 que ela conseguiu colocar de lado o sentimento de raiva como m\u00e3e e ajudar uma menina que ela nem conhecia? Ela foi fiel ao que ela acreditava: Ajudar pessoas. Fidelidade requer fidelidade, integridade confian\u00e7a, sacrif\u00edcio, obedi\u00eancia e muito mais. Corre dentro de voc\u00ea. Requer uma convic\u00e7\u00e3o aos seu princ\u00edpios. Esta convic\u00e7\u00e3o faz com que voc\u00ea coloque os seus princ\u00edpios e cren\u00e7as em pr\u00e1tica, custe o que custar.<\/p>\n<p style=\"text-align: justify;\">Voc\u00ea n\u00e3o teme qualquer consequ\u00eancia nem mede sacrif\u00edcios. Quando voc\u00ea \u00e9 fiel, voc\u00ea se junta a um grupo de pessoas selecionadas e o seu valor como pessoa aumenta, tal como voc\u00ea atrai e \u00e9 atra\u00eddo \u00e0 <a href=\"https:\/\/www.uckg.org\/pt\/por-que-voce-nao-deve-emprestar-seu-credito-para-outras-pessoas\/\">outras pessoas<\/a> que s\u00e3o fi\u00e9is. N\u00e3o \u00e9 o suficiente ser uma boa pessoa, seja fiel as suas cren\u00e7as e princ\u00edpios!<\/p>\n<p style=\"text-align: justify;\"><strong>Deixe-nos ajudar. envie um email para <span style=\"color: #666699;\">&#x72;&#97;ha&#x62;&#x40;uc&#x6b;&#x67;&#46;or&#x67;<\/span>, ligue para a nossa linha 24h em <span style=\"color: #666699;\">020 7272 1010<\/span> ou visite o seu <span style=\"color: #666699;\">Centro de Ajuda<\/span> local onde estaremos \u00e0 sua espera.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Claudia Brito<\/strong><br \/>\n<a title=\"Voc\u00ea tem duas faces?\" href=\"http:\/\/allaboutyouuk.com\/index.php\/category\/portuguese\/\" target=\"_blank\" rel=\"noopener noreferrer\">Allaboutyouuk.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ela se faz de boa para evitar consequ\u00eancias que podem&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[678,655],"tags":[1356,195,1357],"class_list":["post-62856","post","type-post","status-publish","format-standard","hentry","category-claudia-oliveira-brito","category-women","tag-dificil-de-lidar","tag-god","tag-principios-e-crencas"],"_links":{"self":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts\/62856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/comments?post=62856"}],"version-history":[{"count":2,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts\/62856\/revisions"}],"predecessor-version":[{"id":97611,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts\/62856\/revisions\/97611"}],"wp:attachment":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/media?parent=62856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/categories?post=62856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/tags?post=62856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}