{"id":56057,"date":"2015-03-29T13:00:24","date_gmt":"2015-03-29T12:00:24","guid":{"rendered":"http:\/\/www.uckg.org\/pt\/?p=56057"},"modified":"2021-08-23T10:00:06","modified_gmt":"2021-08-23T08:00:06","slug":"de-filhos-para-pais-a-pontinha-do-veu","status":"publish","type":"post","link":"https:\/\/www.uckg.org\/pt\/de-filhos-para-pais-a-pontinha-do-veu\/","title":{"rendered":"De Filhos para pais: A pontinha do \u201cv\u00e9u\u201d"},"content":{"rendered":"<p><a title=\"De Filhos para pais: A pontinha do \u201cv\u00e9u\u201d\" href=\"http:\/\/www.uckg.org\/pt\/wp-content\/uploads\/2015\/03\/DENTRO3.png\" rel=\"\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright wp-image-56058 size-full\" style=\"margin-left: 6px; margin-right: 6px;\" title=\"De Filhos para pais: A pontinha do \u201cv\u00e9u\u201d\" src=\"http:\/\/www.uckg.org\/pt\/wp-content\/uploads\/2015\/03\/DENTRO3.png\" alt=\"De Filhos para pais: A pontinha do \u201cv\u00e9u\u201d\" width=\"308\" height=\"206\" \/><\/a> <strong>Esta express\u00e3o significa que existe muito al\u00e9m daquilo que uma pessoa ou situa\u00e7\u00e3o nos mostram, ou que conseguimos perceber \u00e0 primeira vista.<\/strong> Basicamente s\u00e3o os sinais, ou apenas uma \u201camostra\u201d para algo de maior dimens\u00e3o.<\/p>\n<p><strong>Quando a pontinha do \u201cv\u00e9u\u201d \u00e9 desvendada, e realmente queremos ver al\u00e9m, isto vai implicar uma busca, uma procura atenta, de forma a percebermos, a fundo, quem somos, o que fazemos, e de que forma podemos resolver determinada situa\u00e7\u00e3o.<\/strong><\/p>\n<p><strong>Por exemplo, de que forma percebe o car\u00e1ter de uma pessoa?<\/strong> <strong>Como conhece o seu <a href=\"https:\/\/www.uckg.org\/pt\/o-verdadeiro-amor-envolve-corpo-alma-e-espirito\/\">esp\u00edrito e verdadeiras<\/a> inten\u00e7\u00f5es, se n\u00e3o convive com ela?<\/strong><br \/>\n<strong>Atrav\u00e9s das atitudes!<\/strong> <strong>Se j\u00e1 <a href=\"https:\/\/www.uckg.org\/pt\/atitudes-de-sacrificio-revelam-o-verdadeiro-amor\/\">revela nas atitudes<\/a>, por exemplo, mau temperamento e agressividade, como ser\u00e1 depois de ter confian\u00e7a e intimidade?<\/strong><\/p>\n<p>Muitas vezes deixamos de estar atentos aos sinais, permitindo-nos conduzir pelos sentimentos ou vontade pr\u00f3pria, e acabamos por perder oportunidades de tomar as decis\u00f5es corretas na nossa vida, tanto em rela\u00e7\u00e3o a n\u00f3s mesmas, quanto na \u00e1rea familiar, e no <a title=\"NOSSO FARDO DE CADA DIA\u2026\" href=\"https:\/\/www.uckg.org\/pt\/nosso-fardo-de-cada-dia-2\/\">nosso dia a dia<\/a>.<\/p>\n<p>At\u00e9 mesmo de forma a prevenir situa\u00e7\u00f5es graves de sa\u00fade, que poderiam ter sido evitadas caso estiv\u00e9ssemos atentos a pequenos detalhes, que acabam por revelar-se cruciais.<\/p>\n<p><strong>Por exemplo:<\/strong><\/p>\n<p>&#8211; Muitos pais, por amarem <strong>\u201ccegamente\u201d<\/strong> os seus filhos ou por estarem demasiadamente envolvidos com os seus afazeres, n\u00e3o percebem os \u201csinais\u201d do seu afastamento do lar e da comunh\u00e3o familiar, at\u00e9 que estes se envolvam completamente com estranhos, com maus h\u00e1bitos ou v\u00edcios. Pais e m\u00e3es que atendemos na Igreja, at\u00e9 nos dizem que os seus filhos jamais fariam tal coisa\u2026 negando-se a assumirem a realidade!<\/p>\n<p>&#8211; Outros tantos casos relacionam-se com pessoas \u00e0 procura do parceiro ideal. Talvez depois de muitos anos \u00e0 espera, aquilo que deveriam ser <strong>\u201csinais<\/strong>\u201d passam a ser consideradas como atitudes \u201cnormais\u201d: Uma palavra rude; um desequil\u00edbrio; uma sugest\u00e3o contr\u00e1ria \u00e0 f\u00e9 verdadeira\u2026 Se realmente a pessoa n\u00e3o est\u00e1 atenta a vigilante, acaba por se render a uma situa\u00e7\u00e3o, cujos frutos se revelar\u00e3o amargos no futuro.<\/p>\n<p>Isto n\u00e3o significa que sejamos pessoas desconfiadas, ou que conseguiremos \u201ccontrolar\u201d tudo. Definitivamente, n\u00e3o! H\u00e1 escolhas que apenas a pr\u00f3pria pessoa faz, sem <a title=\"O bom influenciador sabe exatamente o que pensa e como agir\" href=\"https:\/\/www.uckg.org\/pt\/o-bom-influenciador-sabe-exatamente-o-que-pensa-e-como-agir\/\">a influ\u00eancia de ningu\u00e9m<\/a>!<\/p>\n<p>Mas se estivermos atentas, vigilantes, apercebidas, mais rapidamente conseguimos perceber \u2013 e reverter \u2013 uma \u201carmadilha\u201d que se esteja a formar diante de n\u00f3s.<\/p>\n<p><strong>Como num \u201cringue\u201d! J\u00e1 reparou em um ringue, a forma como os lutadores est\u00e3o atentos, antecipando at\u00e9 cada movimento e golpes do advers\u00e1rio? N\u00e3o h\u00e1 lugar para distra\u00e7\u00f5es!<\/strong><\/p>\n<p>E perguntar\u00e1, talvez: <strong>\u201cMas ser\u00e1 que Deus n\u00e3o nos livra do mal?\u201d. Sim, sem d\u00favida, mas Ele jamais escolher\u00e1 em nosso lugar!<\/strong><\/p>\n<p><strong>Sobretudo, Ele respeitar\u00e1 as nossas escolhas quando estas n\u00e3o s\u00e3o submetidas \u00e0 Sua vontade. Ele \u00e9 o princ\u00edpio da justi\u00e7a, e por isso n\u00e3o pode influenciar no livre arb\u00edtrio que Ele pr\u00f3prio nos concedeu!<\/strong><\/p>\n<p><strong><em>Sede s\u00f3brios e vigilantes. O diabo, vosso advers\u00e1rio, anda em derredor, como le\u00e3o que ruge procurando algu\u00e9m para devorar\u2026\u201d<\/em> <\/strong>(I Pe.5:8)<\/p>\n<p>Se permanecermos vigilantes e atentas aos sinais \u2013 sem n\u00f3s enganarmos a n\u00f3s mesmas \u2013 com certeza estaremos mais aptas a perceber onde falhamos, e trabalhar para acertarmos, ajudando igualmente quem nos rodeia.<\/p>\n<p><strong><a href=\"http:\/\/vivifreitas.me\" target=\"_blank\" rel=\"noopener\">Viviane Freitas<\/a><\/strong><br \/>\n<a title=\"De Filhos para pais: A pontinha do \u201cv\u00e9u\u201d\" href=\"&#109;&#x61;i&#x6c;t&#x6f;:&#x62;l&#x6f;g&#64;&#x76;&#105;&#x76;i&#x66;r&#x65;i&#x74;a&#x73;.&#109;&#x65;\" rel=\"\">&#x62;&#108;og&#x40;&#x76;iv&#x69;&#x66;&#114;ei&#x74;&#97;s.&#x6d;&#x65;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta express\u00e3o significa que existe muito al\u00e9m daquilo que uma pessoa ou situa\u00e7\u00e3o nos mostram, ou que conseguimos perceber \u00e0 primeira vista.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[655],"tags":[4621,4620],"class_list":["post-56057","post","type-post","status-publish","format-standard","hentry","category-women","tag-a-influencia-de-ninguem","tag-nosso-dia-a-dia"],"_links":{"self":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts\/56057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/comments?post=56057"}],"version-history":[{"count":2,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts\/56057\/revisions"}],"predecessor-version":[{"id":97161,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts\/56057\/revisions\/97161"}],"wp:attachment":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/media?parent=56057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/categories?post=56057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/tags?post=56057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}