{"id":44781,"date":"2012-11-04T05:57:39","date_gmt":"2012-11-04T05:57:39","guid":{"rendered":"http:\/\/www.uckg.org\/pt\/?p=44781"},"modified":"2021-07-19T11:52:10","modified_gmt":"2021-07-19T09:52:10","slug":"amor-bandido","status":"publish","type":"post","link":"https:\/\/www.uckg.org\/pt\/amor-bandido\/","title":{"rendered":"Amor Bandido\u2026"},"content":{"rendered":"<p style=\"text-align: center;\"><a title=\"Amor Bandido\u2026\" href=\"https:\/\/www.uckg.org\/pt\/amor-bandido\/casal-se-olhando\/\" rel=\"\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-44782\" title=\"casal se olhando\" src=\"http:\/\/www.uckg.org\/pt\/wp-content\/uploads\/2012\/11\/casal-se-olhando.jpg\" alt=\"\" width=\"616\" height=\"608\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Ela tinha um sonho de casar e ter uma fam\u00edlia, <a title=\"3 sinais de que j\u00e1 estamos no Fim dos Tempos\" href=\"https:\/\/www.uckg.org\/pt\/3-sinais-de-que-ja-estamos-no-fim-dos-tempos\/\">mas o tempo <\/a>estava passando e nada parecia acontecer nessa \u00e1rea da sua vida&#8230; At\u00e9 que um dia ela percebeu seus olhares\u2026 Ele n\u00e3o era nem o seu tipo, mas come\u00e7aram a conversar e quando menos esperava, se viu apaixonada.<br \/>\nDecidiram namorar, tudo dentro dos conformes, ele a pediu em namoro na presen\u00e7a de seus pais e tudo parecia perfeito, at\u00e9 que com o tempo, pouco a pouco, ele se transformou\u2026 Um rapaz grosseiro tomou lugar do gentil que havia conhecido. Um mand\u00e3o e abusivo, tomou lugar daquele t\u00e3o respeitador de suas opini\u00f5es.<\/p>\n<p>A coisa foi piorando ao ponto dela n\u00e3o reconhecer mais aquele estranho que agora dava sorriso na frente de todos segurando sua m\u00e3o com carinho dissimulado, mas por tr\u00e1s a maltratava e a abusava verbalmente. Mas apesar de tudo isso, ela n\u00e3o quer perde-lo. Como <a title=\"Eu quero logoooo!\" href=\"https:\/\/www.uckg.org\/pt\/eu-quero-logoooo\/\">iniciar tudo de novo<\/a>? Como recome\u00e7ar? Nunca vai encontrar <a href=\"https:\/\/www.uckg.org\/pt\/por-que-voce-nao-deve-emprestar-seu-credito-para-outras-pessoas\/\">outra pessoa<\/a>, ela pensa.<\/p>\n<p>Queridas amigas, os sinais est\u00e3o evidentes e sabe o que tenho pra te dizer?<\/p>\n<p>Voc\u00ea merece melhor que isso! Use sua f\u00e9, seja violenta com seu cora\u00e7\u00e3o bandido e enganador e tome a decis\u00e3o dolorosa que vai no fim, te aben\u00e7oar.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>nandabezerra.com | nb&#64;&#117;&#99;&#x6b;&#x67;&#x2e;&#x6f;&#x72;g<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ela tinha um sonho de casar e ter uma fam\u00edlia, mas o tempo estava passando e nada parecia acontecer nessa \u00e1rea da sua vida&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[655,656],"tags":[3891,2495],"class_list":["post-44781","post","type-post","status-publish","format-standard","hentry","category-women","category-nanda-bezerra","tag-iniciar-tudo-de-novo","tag-mas-o-tempo"],"_links":{"self":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts\/44781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/comments?post=44781"}],"version-history":[{"count":2,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts\/44781\/revisions"}],"predecessor-version":[{"id":96464,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/posts\/44781\/revisions\/96464"}],"wp:attachment":[{"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/media?parent=44781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/categories?post=44781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uckg.org\/pt\/wp-json\/wp\/v2\/tags?post=44781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}