{"id":62550,"date":"2019-05-22T23:45:17","date_gmt":"2019-05-22T21:45:17","guid":{"rendered":"https:\/\/www.uckg.org\/es\/?p=62550"},"modified":"2021-12-03T15:42:47","modified_gmt":"2021-12-03T14:42:47","slug":"ayuno-de-daniel-dia-4","status":"publish","type":"post","link":"https:\/\/www.uckg.org\/es\/ayuno-de-daniel-dia-4\/","title":{"rendered":"Tareas del Ayuno de Daniel &#8211; D\u00eda 4"},"content":{"rendered":"<p><a href=\"https:\/\/www.uckg.org\/es\/wp-content\/uploads\/2018\/08\/FDanielDay4.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-64385\" src=\"https:\/\/www.uckg.org\/es\/wp-content\/uploads\/2018\/08\/FDanielDay4.png\" alt=\"\" width=\"676\" height=\"291\" title=\"\"><\/a><\/p>\n<p class=\"p2\" style=\"text-align: justify;\">Sabemos que algunas personas se sienten desanimadas y quieren renunciar porque no fueron capaces de lograr todas las tareas anteriores. Se preguntan si hay una raz\u00f3n por la que deber\u00edan seguir adelante. La respuesta es: \u00a1S\u00ed, la hay! No te partir\u00e1 un rayo en dos si no haces una tarea. Es bueno que lo intentes y las hagas todas, pero si no puedes, contin\u00faa y haz lo que no pudiste al d\u00eda siguiente. Es mejor seguir adelante que darse por vencido.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">La tabla de tareas para hoy est\u00e1 al lado. Uno de los principales objetivos para hoy es pensar en tus ansiedades; luchar contra ellas y no dejar que nada te robe tu paz, tu fe ni tu dinero. La gente compra muchas cosas, especialmente durante las vacaciones, movidos por la ansiedad creada por los anuncios y las expectativas sociales. Resiste. Usa tu cabeza.<\/p>\n<p class=\"p2\" style=\"text-align: justify;\">En cuanto a las relaciones, no hay nadie que te conozca mejor que aquellos que viven contigo o te rodean constantemente. Ellos ven lo bueno en ti, pero tambi\u00e9n conocen las malas costumbres que, en ocasiones, los irritan, por lo tanto, hoy, te invitamos a enfrentar la verdad en humildad. Que ellos te confiesen qu\u00e9 te hace ser una persona dif\u00edcil con la que tratar.<\/p>\n<p class=\"p3\" style=\"text-align: justify;\">Y como dijimos en el art\u00edculo de ayer sobre c\u00f3mo acabar con una mala costumbre, es importante que comiences a practicar una buena para sustituir la mala que ten\u00edas. Por ejemplo, si quiero acabar con la mala costumbre de hacer las cosas en el \u00faltimo momento, voy a crear la costumbre buena de organizar mi tiempo y agenda, sin dejar que algo importante se haga con prisa cuando el tiempo es limitado.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.uckg.org\/es\/wp-content\/uploads\/2019\/05\/21DaysTasks-Spa4.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-64403\" src=\"https:\/\/www.uckg.org\/es\/wp-content\/uploads\/2019\/05\/21DaysTasks-Spa4.jpg\" alt=\"\" width=\"1024\" height=\"576\" title=\"\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabemos que algunas personas se sienten desanimadas y quieren renunciar porque no fueron capaces de lograr todas las tareas anteriores. Se preguntan si hay una raz\u00f3n por la que deber\u00edan seguir adelante. La respuesta es: \u00a1S\u00ed, la hay! No te partir\u00e1 un rayo en dos si no haces una tarea. Es bueno que lo intentes [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":64385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[634,1227,1],"tags":[4003,4004],"class_list":["post-62550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-21-dias-de-ayuno","category-obispo-alvaro-lima","category-uncategorised","tag-durante-las-vacaciones","tag-el-tiempo-es-limitado"],"_links":{"self":[{"href":"https:\/\/www.uckg.org\/es\/wp-json\/wp\/v2\/posts\/62550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uckg.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uckg.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uckg.org\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uckg.org\/es\/wp-json\/wp\/v2\/comments?post=62550"}],"version-history":[{"count":4,"href":"https:\/\/www.uckg.org\/es\/wp-json\/wp\/v2\/posts\/62550\/revisions"}],"predecessor-version":[{"id":64415,"href":"https:\/\/www.uckg.org\/es\/wp-json\/wp\/v2\/posts\/62550\/revisions\/64415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uckg.org\/es\/wp-json\/wp\/v2\/media\/64385"}],"wp:attachment":[{"href":"https:\/\/www.uckg.org\/es\/wp-json\/wp\/v2\/media?parent=62550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uckg.org\/es\/wp-json\/wp\/v2\/categories?post=62550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uckg.org\/es\/wp-json\/wp\/v2\/tags?post=62550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}